{"id":11033,"count":8,"description":"Stani Kulechov \u0e40\u0e1b\u0e25\u0e35\u0e48\u0e22\u0e19\u0e08\u0e32\u0e01\u0e19\u0e31\u0e01\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e0b\u0e2d\u0e1f\u0e15\u0e4c\u0e41\u0e27\u0e23\u0e4c\u0e2a\u0e39\u0e48\u0e1c\u0e39\u0e49\u0e19\u0e33 DeFi \u0e23\u0e30\u0e14\u0e31\u0e1a\u0e42\u0e25\u0e01 \u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e40\u0e1b\u0e34\u0e14\u0e40\u0e1c\u0e22\u0e01\u0e25\u0e22\u0e38\u0e17\u0e18\u0e4c\u0e01\u0e32\u0e23\u0e40\u0e15\u0e34\u0e1a\u0e42\u0e15\u0e17\u0e35\u0e48\u0e19\u0e48\u0e32\u0e08\u0e31\u0e1a\u0e15\u0e32\u0e21\u0e2d\u0e07\u0e43\u0e19\u0e27\u0e07\u0e01\u0e32\u0e23\u0e04\u0e23\u0e34\u0e1b\u0e42\u0e15!","link":"https:\/\/cryptozen.asia\/th\/tag\/stani-kulechov\/","name":"Stani Kulechov","slug":"stani-kulechov","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.6 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Stani Kulechov News - CryptoZen<\/title>\n<meta name=\"description\" content=\"Stani Kulechov \u0e40\u0e1b\u0e25\u0e35\u0e48\u0e22\u0e19\u0e08\u0e32\u0e01\u0e19\u0e31\u0e01\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e0b\u0e2d\u0e1f\u0e15\u0e4c\u0e41\u0e27\u0e23\u0e4c\u0e2a\u0e39\u0e48\u0e1c\u0e39\u0e49\u0e19\u0e33 DeFi \u0e23\u0e30\u0e14\u0e31\u0e1a\u0e42\u0e25\u0e01 \u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e40\u0e1b\u0e34\u0e14\u0e40\u0e1c\u0e22\u0e01\u0e25\u0e22\u0e38\u0e17\u0e18\u0e4c\u0e01\u0e32\u0e23\u0e40\u0e15\u0e34\u0e1a\u0e42\u0e15\u0e17\u0e35\u0e48\u0e19\u0e48\u0e32\u0e08\u0e31\u0e1a\u0e15\u0e32\u0e21\u0e2d\u0e07\u0e43\u0e19\u0e27\u0e07\u0e01\u0e32\u0e23\u0e04\u0e23\u0e34\u0e1b\u0e42\u0e15!\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/cryptozen.asia\/th\/tag\/stani-kulechov\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Stani Kulechov News - CryptoZen\" \/>\n<meta property=\"og:description\" content=\"Stani Kulechov \u0e40\u0e1b\u0e25\u0e35\u0e48\u0e22\u0e19\u0e08\u0e32\u0e01\u0e19\u0e31\u0e01\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e0b\u0e2d\u0e1f\u0e15\u0e4c\u0e41\u0e27\u0e23\u0e4c\u0e2a\u0e39\u0e48\u0e1c\u0e39\u0e49\u0e19\u0e33 DeFi \u0e23\u0e30\u0e14\u0e31\u0e1a\u0e42\u0e25\u0e01 \u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e40\u0e1b\u0e34\u0e14\u0e40\u0e1c\u0e22\u0e01\u0e25\u0e22\u0e38\u0e17\u0e18\u0e4c\u0e01\u0e32\u0e23\u0e40\u0e15\u0e34\u0e1a\u0e42\u0e15\u0e17\u0e35\u0e48\u0e19\u0e48\u0e32\u0e08\u0e31\u0e1a\u0e15\u0e32\u0e21\u0e2d\u0e07\u0e43\u0e19\u0e27\u0e07\u0e01\u0e32\u0e23\u0e04\u0e23\u0e34\u0e1b\u0e42\u0e15!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/cryptozen.asia\/th\/tag\/stani-kulechov\/\" \/>\n<meta property=\"og:site_name\" content=\"CryptoZen\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\/\/cryptozen.asia\/th\/tag\/stani-kulechov\/\",\"url\":\"https:\/\/cryptozen.asia\/th\/tag\/stani-kulechov\/\",\"name\":\"Stani Kulechov News - CryptoZen\",\"isPartOf\":{\"@id\":\"https:\/\/cryptozen.asia\/th\/#website\"},\"description\":\"Stani Kulechov \u0e40\u0e1b\u0e25\u0e35\u0e48\u0e22\u0e19\u0e08\u0e32\u0e01\u0e19\u0e31\u0e01\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e0b\u0e2d\u0e1f\u0e15\u0e4c\u0e41\u0e27\u0e23\u0e4c\u0e2a\u0e39\u0e48\u0e1c\u0e39\u0e49\u0e19\u0e33 DeFi \u0e23\u0e30\u0e14\u0e31\u0e1a\u0e42\u0e25\u0e01 \u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e40\u0e1b\u0e34\u0e14\u0e40\u0e1c\u0e22\u0e01\u0e25\u0e22\u0e38\u0e17\u0e18\u0e4c\u0e01\u0e32\u0e23\u0e40\u0e15\u0e34\u0e1a\u0e42\u0e15\u0e17\u0e35\u0e48\u0e19\u0e48\u0e32\u0e08\u0e31\u0e1a\u0e15\u0e32\u0e21\u0e2d\u0e07\u0e43\u0e19\u0e27\u0e07\u0e01\u0e32\u0e23\u0e04\u0e23\u0e34\u0e1b\u0e42\u0e15!\",\"breadcrumb\":{\"@id\":\"https:\/\/cryptozen.asia\/th\/tag\/stani-kulechov\/#breadcrumb\"},\"inLanguage\":\"th\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/cryptozen.asia\/th\/tag\/stani-kulechov\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/cryptozen.asia\/th\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Stani Kulechov\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/cryptozen.asia\/th\/#website\",\"url\":\"https:\/\/cryptozen.asia\/th\/\",\"name\":\"CryptoZen\",\"description\":\"\u0e02\u0e48\u0e32\u0e27\u0e04\u0e23\u0e34\u0e1b\u0e42\u0e15\u0e40\u0e04\u0e2d\u0e40\u0e23\u0e19\u0e0b\u0e35\u0e0a\u0e31\u0e49\u0e19\u0e19\u0e33\u0e17\u0e35\u0e48\u0e44\u0e14\u0e49\u0e23\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e2a\u0e48\u0e07\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e42\u0e14\u0e22 AI\",\"publisher\":{\"@id\":\"https:\/\/cryptozen.asia\/th\/#organization\"},\"alternateName\":\"CZ\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/cryptozen.asia\/th\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"th\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/cryptozen.asia\/th\/#organization\",\"name\":\"CryptoZen\",\"alternateName\":\"CZ\",\"url\":\"https:\/\/cryptozen.asia\/th\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"th\",\"@id\":\"https:\/\/cryptozen.asia\/th\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/cryptozen.asia\/th\/wp-content\/uploads\/sites\/26\/2025\/05\/azen_preview2-1.png\",\"contentUrl\":\"https:\/\/cryptozen.asia\/th\/wp-content\/uploads\/sites\/26\/2025\/05\/azen_preview2-1.png\",\"width\":600,\"height\":600,\"caption\":\"CryptoZen\"},\"image\":{\"@id\":\"https:\/\/cryptozen.asia\/th\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Stani Kulechov News - CryptoZen","description":"Stani Kulechov \u0e40\u0e1b\u0e25\u0e35\u0e48\u0e22\u0e19\u0e08\u0e32\u0e01\u0e19\u0e31\u0e01\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e0b\u0e2d\u0e1f\u0e15\u0e4c\u0e41\u0e27\u0e23\u0e4c\u0e2a\u0e39\u0e48\u0e1c\u0e39\u0e49\u0e19\u0e33 DeFi \u0e23\u0e30\u0e14\u0e31\u0e1a\u0e42\u0e25\u0e01 \u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e40\u0e1b\u0e34\u0e14\u0e40\u0e1c\u0e22\u0e01\u0e25\u0e22\u0e38\u0e17\u0e18\u0e4c\u0e01\u0e32\u0e23\u0e40\u0e15\u0e34\u0e1a\u0e42\u0e15\u0e17\u0e35\u0e48\u0e19\u0e48\u0e32\u0e08\u0e31\u0e1a\u0e15\u0e32\u0e21\u0e2d\u0e07\u0e43\u0e19\u0e27\u0e07\u0e01\u0e32\u0e23\u0e04\u0e23\u0e34\u0e1b\u0e42\u0e15!","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/cryptozen.asia\/th\/tag\/stani-kulechov\/","og_locale":"en_US","og_type":"article","og_title":"Stani Kulechov News - CryptoZen","og_description":"Stani Kulechov \u0e40\u0e1b\u0e25\u0e35\u0e48\u0e22\u0e19\u0e08\u0e32\u0e01\u0e19\u0e31\u0e01\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e0b\u0e2d\u0e1f\u0e15\u0e4c\u0e41\u0e27\u0e23\u0e4c\u0e2a\u0e39\u0e48\u0e1c\u0e39\u0e49\u0e19\u0e33 DeFi \u0e23\u0e30\u0e14\u0e31\u0e1a\u0e42\u0e25\u0e01 \u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e40\u0e1b\u0e34\u0e14\u0e40\u0e1c\u0e22\u0e01\u0e25\u0e22\u0e38\u0e17\u0e18\u0e4c\u0e01\u0e32\u0e23\u0e40\u0e15\u0e34\u0e1a\u0e42\u0e15\u0e17\u0e35\u0e48\u0e19\u0e48\u0e32\u0e08\u0e31\u0e1a\u0e15\u0e32\u0e21\u0e2d\u0e07\u0e43\u0e19\u0e27\u0e07\u0e01\u0e32\u0e23\u0e04\u0e23\u0e34\u0e1b\u0e42\u0e15!","og_url":"https:\/\/cryptozen.asia\/th\/tag\/stani-kulechov\/","og_site_name":"CryptoZen","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/cryptozen.asia\/th\/tag\/stani-kulechov\/","url":"https:\/\/cryptozen.asia\/th\/tag\/stani-kulechov\/","name":"Stani Kulechov News - CryptoZen","isPartOf":{"@id":"https:\/\/cryptozen.asia\/th\/#website"},"description":"Stani Kulechov \u0e40\u0e1b\u0e25\u0e35\u0e48\u0e22\u0e19\u0e08\u0e32\u0e01\u0e19\u0e31\u0e01\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e0b\u0e2d\u0e1f\u0e15\u0e4c\u0e41\u0e27\u0e23\u0e4c\u0e2a\u0e39\u0e48\u0e1c\u0e39\u0e49\u0e19\u0e33 DeFi \u0e23\u0e30\u0e14\u0e31\u0e1a\u0e42\u0e25\u0e01 \u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e40\u0e1b\u0e34\u0e14\u0e40\u0e1c\u0e22\u0e01\u0e25\u0e22\u0e38\u0e17\u0e18\u0e4c\u0e01\u0e32\u0e23\u0e40\u0e15\u0e34\u0e1a\u0e42\u0e15\u0e17\u0e35\u0e48\u0e19\u0e48\u0e32\u0e08\u0e31\u0e1a\u0e15\u0e32\u0e21\u0e2d\u0e07\u0e43\u0e19\u0e27\u0e07\u0e01\u0e32\u0e23\u0e04\u0e23\u0e34\u0e1b\u0e42\u0e15!","breadcrumb":{"@id":"https:\/\/cryptozen.asia\/th\/tag\/stani-kulechov\/#breadcrumb"},"inLanguage":"th"},{"@type":"BreadcrumbList","@id":"https:\/\/cryptozen.asia\/th\/tag\/stani-kulechov\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/cryptozen.asia\/th\/"},{"@type":"ListItem","position":2,"name":"Stani Kulechov"}]},{"@type":"WebSite","@id":"https:\/\/cryptozen.asia\/th\/#website","url":"https:\/\/cryptozen.asia\/th\/","name":"CryptoZen","description":"\u0e02\u0e48\u0e32\u0e27\u0e04\u0e23\u0e34\u0e1b\u0e42\u0e15\u0e40\u0e04\u0e2d\u0e40\u0e23\u0e19\u0e0b\u0e35\u0e0a\u0e31\u0e49\u0e19\u0e19\u0e33\u0e17\u0e35\u0e48\u0e44\u0e14\u0e49\u0e23\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e2a\u0e48\u0e07\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e42\u0e14\u0e22 AI","publisher":{"@id":"https:\/\/cryptozen.asia\/th\/#organization"},"alternateName":"CZ","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/cryptozen.asia\/th\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"th"},{"@type":"Organization","@id":"https:\/\/cryptozen.asia\/th\/#organization","name":"CryptoZen","alternateName":"CZ","url":"https:\/\/cryptozen.asia\/th\/","logo":{"@type":"ImageObject","inLanguage":"th","@id":"https:\/\/cryptozen.asia\/th\/#\/schema\/logo\/image\/","url":"https:\/\/cryptozen.asia\/th\/wp-content\/uploads\/sites\/26\/2025\/05\/azen_preview2-1.png","contentUrl":"https:\/\/cryptozen.asia\/th\/wp-content\/uploads\/sites\/26\/2025\/05\/azen_preview2-1.png","width":600,"height":600,"caption":"CryptoZen"},"image":{"@id":"https:\/\/cryptozen.asia\/th\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/cryptozen.asia\/th\/wp-json\/wp\/v2\/tags\/11033","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cryptozen.asia\/th\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/cryptozen.asia\/th\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/cryptozen.asia\/th\/wp-json\/wp\/v2\/posts?tags=11033"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}